{"id":258,"date":"2026-07-22T18:49:48","date_gmt":"2026-07-22T18:49:48","guid":{"rendered":"https:\/\/ecokompass.com\/?page_id=258"},"modified":"2026-08-31T19:15:42","modified_gmt":"2026-08-31T19:15:42","slug":"reembolso_devoluciones","status":"publish","type":"page","link":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/","title":{"rendered":"Returns and refunds policy"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Nuestra pol\u00edtica de devoluciones y reembolsos tiene una duraci\u00f3n de 30 d\u00edas.<br>Si han pasado 30 d\u00edas desde tu compra, no podemos ofrecer un reembolso completo ni un cambio del producto.<br><br>Para poder acogerse a una devoluci\u00f3n, el art\u00edculo debe estar sin usar y en las mismas condiciones en que se recibi\u00f3. Adem\u00e1s, debe estar en su embalaje original.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para completar la devoluci\u00f3n, necesitamos \u00fanicamente el n\u00famero de pedido suministrado en el momento de la compra.<br>Por favor, no env\u00ede su compra de vuelta al fabricante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se podr\u00e1 realizar cambio o devoluci\u00f3n en los siguientes casos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cualquier art\u00edculo que no est\u00e9 en su condici\u00f3n original, que est\u00e9 da\u00f1ado o que falten partes por motivos no atribuibles a nosotros.<\/li>\n\n\n\n<li>Cualquier art\u00edculo que se devuelva m\u00e1s de 30 d\u00edas despu\u00e9s de la entrega.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reembolsos<\/strong><br>Una vez que recibamos su devoluci\u00f3n y la inspeccionemos, le enviaremos un correo electr\u00f3nico para notificar que hemos recibido el art\u00edculo devuelto. Tambi\u00e9n le notificaremos sobre la aprobaci\u00f3n o el rechazo de su reembolso.<br>Si se aprueba, entonces se procesar\u00e1 el reembolso y se aplicar\u00e1 autom\u00e1ticamente un abono a la tarjeta de cr\u00e9dito o al m\u00e9todo de pago original, dentro de un cierto n\u00famero de d\u00edas.<br><strong>Reembolsos atrasados o faltantes<\/strong><br>Si a\u00fan no ha recibido el reembolso, primero vuelva a revisar su cuenta bancaria y en su caso, enviaremos orden de reembolso realizada para que pueda reclamar a su entidad bancaria si es el caso.<br>Luego, contacte con la empresa de su tarjeta de cr\u00e9dito; puede tomar un tiempo antes de que el reembolso se registre oficialmente.<br>A continuaci\u00f3n, contacte con su banco. A menudo hay un tiempo de procesamiento antes de que el reembolso se publique.<br>Si ha hecho todo esto y aun as\u00ed no ha recibido su reembolso, por favor cont\u00e1ctenos en info@ecokompass.com<br><strong>Art\u00edculos en promoci\u00f3n<\/strong><br>Solo los art\u00edculos con precio regular pueden reembolsarse. Los art\u00edculos en promoci\u00f3n no pueden reembolsarse.<br><strong>Cambios<\/strong><br>Solo reemplazamos los art\u00edculos si est\u00e1n defectuosos o da\u00f1ados en el momento de su recepci\u00f3n. Si necesita cambiarlo por el mismo art\u00edculo, env\u00edenos un correo electr\u00f3nico a info@ecokompass.com y env\u00ede su art\u00edculo a: la direcci\u00f3n de devoluci\u00f3n que le indicaremos en nuestra respuesta.<br><strong>Regalos<\/strong><br>Si el art\u00edculo se marc\u00f3 como regalo al momento de la compra y se envi\u00f3 directamente a usted, recibir\u00e1 un cr\u00e9dito de regalo por el valor de su devoluci\u00f3n. Una vez que se reciba el art\u00edculo devuelto, le enviaremos por correo un certificado de regalo.<br>Si el art\u00edculo no se marc\u00f3 como regalo al momento de la compra, o si la persona que regal\u00f3 hizo que el pedido se enviara a s\u00ed misma para d\u00e1rselo m\u00e1s tarde, enviaremos un reembolso a la persona que hizo el regalo y ella se enterar\u00e1 de su devoluci\u00f3n.<br><strong>Devoluciones de env\u00edos<\/strong><br>Para devolver tu producto, debes enviarlo por correo a: la direcci\u00f3n de devoluci\u00f3n que le indicaremos en nuestra respuesta.<br>Ser\u00e1 responsable de pagar sus propios costos de env\u00edo para devolver tu art\u00edculo. Los costos de env\u00edo no son reembolsables. Si recibe un reembolso, el costo del env\u00edo de devoluci\u00f3n se descontar\u00e1 de su reembolso.<br>Dependiendo de d\u00f3nde viva, el tiempo que puede tardar su producto cambiado en llegar puede variar.<br>Si devuelves art\u00edculos m\u00e1s caros, podr\u00eda considerar usar un servicio de env\u00edo rastreable o comprar un seguro de env\u00edo. No garantizamos que recibiremos su art\u00edculo devuelto.<br><strong>\u00bfNecesitas ayuda?<\/strong><br>Cont\u00e1ctenos en info@ecokompass.com para preguntas relacionadas con reembolsos y devoluciones.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nuestra pol\u00edtica de devoluciones y reembolsos tiene una duraci\u00f3n de 30 d\u00edas.Si han pasado 30 d\u00edas desde tu compra, no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":254,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-258","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nuestra pol\u00edtica de devoluciones y reembolsos tiene una duraci\u00f3n de 30 d\u00edas.Si han pasado 30 d\u00edas desde tu compra, no podemos ofrecer un reembolso completo ni un cambio del producto.Para poder acogerse a una devoluci\u00f3n, el art\u00edculo debe estar sin usar y en las mismas condiciones en que se recibi\u00f3. Adem\u00e1s, debe estar en su\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"EcoKOMPASS - Noticias  y Consejos de Salud Natural\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pol\u00edtica de devoluciones y reembolsos - EcoKOMPASS\" \/>\n\t\t<meta property=\"og:description\" content=\"Nuestra pol\u00edtica de devoluciones y reembolsos tiene una duraci\u00f3n de 30 d\u00edas.Si han pasado 30 d\u00edas desde tu compra, no podemos ofrecer un reembolso completo ni un cambio del producto.Para poder acogerse a una devoluci\u00f3n, el art\u00edculo debe estar sin usar y en las mismas condiciones en que se recibi\u00f3. Adem\u00e1s, debe estar en su\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ecokompass.com\/wp-content\/uploads\/2026\/07\/cropped-IMG_0654.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ecokompass.com\/wp-content\/uploads\/2026\/07\/cropped-IMG_0654.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"605\" \/>\n\t\t<meta property=\"og:image:height\" content=\"699\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-22T18:49:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-08-31T19:15:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pol\u00edtica de devoluciones y reembolsos - EcoKOMPASS\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nuestra pol\u00edtica de devoluciones y reembolsos tiene una duraci\u00f3n de 30 d\u00edas.Si han pasado 30 d\u00edas desde tu compra, no podemos ofrecer un reembolso completo ni un cambio del producto.Para poder acogerse a una devoluci\u00f3n, el art\u00edculo debe estar sin usar y en las mismas condiciones en que se recibi\u00f3. Adem\u00e1s, debe estar en su\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ecokompass.com\/wp-content\/uploads\/2026\/07\/cropped-IMG_0654.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/reembolso_devoluciones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecokompass.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/#listItem\",\"name\":\"ECOTienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/#listItem\",\"position\":2,\"name\":\"ECOTienda\",\"item\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/reembolso_devoluciones\\\/#listItem\",\"name\":\"Pol\\u00edtica de devoluciones y reembolsos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/reembolso_devoluciones\\\/#listItem\",\"position\":3,\"name\":\"Pol\\u00edtica de devoluciones y reembolsos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/#listItem\",\"name\":\"ECOTienda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/#organization\",\"name\":\"EcoKOMPASS\",\"description\":\"Noticias  y Consejos de Salud Natural\",\"url\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecokompass.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_0654.jpg\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/reembolso_devoluciones\\\/#organizationLogo\",\"width\":893,\"height\":839},\"image\":{\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/reembolso_devoluciones\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/reembolso_devoluciones\\\/#webpage\",\"url\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/reembolso_devoluciones\\\/\",\"name\":\"Pol\\u00edtica de devoluciones y reembolsos - EcoKOMPASS\",\"description\":\"Nuestra pol\\u00edtica de devoluciones y reembolsos tiene una duraci\\u00f3n de 30 d\\u00edas.Si han pasado 30 d\\u00edas desde tu compra, no podemos ofrecer un reembolso completo ni un cambio del producto.Para poder acogerse a una devoluci\\u00f3n, el art\\u00edculo debe estar sin usar y en las mismas condiciones en que se recibi\\u00f3. Adem\\u00e1s, debe estar en su\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/tienda\\\/reembolso_devoluciones\\\/#breadcrumblist\"},\"datePublished\":\"2026-07-22T18:49:48+00:00\",\"dateModified\":\"2026-08-31T19:15:42+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/\",\"name\":\"EcoKOMPASS\",\"description\":\"Noticias  y Consejos de Salud Natural\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pol\u00edtica de devoluciones y reembolsos - EcoKOMPASS","description":"Nuestra pol\u00edtica de devoluciones y reembolsos tiene una duraci\u00f3n de 30 d\u00edas.Si han pasado 30 d\u00edas desde tu compra, no podemos ofrecer un reembolso completo ni un cambio del producto.Para poder acogerse a una devoluci\u00f3n, el art\u00edculo debe estar sin usar y en las mismas condiciones en que se recibi\u00f3. Adem\u00e1s, debe estar en su","canonical_url":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/ecokompass.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en\/tienda\/#listItem","name":"ECOTienda"}},{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en\/tienda\/#listItem","position":2,"name":"ECOTienda","item":"https:\/\/ecokompass.com\/en\/tienda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/#listItem","name":"Pol\u00edtica de devoluciones y reembolsos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/#listItem","position":3,"name":"Pol\u00edtica de devoluciones y reembolsos","previousItem":{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en\/tienda\/#listItem","name":"ECOTienda"}}]},{"@type":"Organization","@id":"https:\/\/ecokompass.com\/en\/#organization","name":"EcoKOMPASS","description":"Noticias  y Consejos de Salud Natural","url":"https:\/\/ecokompass.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/ecokompass.com\/wp-content\/uploads\/2026\/07\/IMG_0654.jpg","@id":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/#organizationLogo","width":893,"height":839},"image":{"@id":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/#webpage","url":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/","name":"Pol\u00edtica de devoluciones y reembolsos - EcoKOMPASS","description":"Nuestra pol\u00edtica de devoluciones y reembolsos tiene una duraci\u00f3n de 30 d\u00edas.Si han pasado 30 d\u00edas desde tu compra, no podemos ofrecer un reembolso completo ni un cambio del producto.Para poder acogerse a una devoluci\u00f3n, el art\u00edculo debe estar sin usar y en las mismas condiciones en que se recibi\u00f3. Adem\u00e1s, debe estar en su","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/ecokompass.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/#breadcrumblist"},"datePublished":"2026-07-22T18:49:48+00:00","dateModified":"2026-08-31T19:15:42+00:00"},{"@type":"WebSite","@id":"https:\/\/ecokompass.com\/en\/#website","url":"https:\/\/ecokompass.com\/en\/","name":"EcoKOMPASS","description":"Noticias  y Consejos de Salud Natural","inLanguage":"en-GB","publisher":{"@id":"https:\/\/ecokompass.com\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"EcoKOMPASS - Noticias  y Consejos de Salud Natural","og:type":"article","og:title":"Pol\u00edtica de devoluciones y reembolsos - EcoKOMPASS","og:description":"Nuestra pol\u00edtica de devoluciones y reembolsos tiene una duraci\u00f3n de 30 d\u00edas.Si han pasado 30 d\u00edas desde tu compra, no podemos ofrecer un reembolso completo ni un cambio del producto.Para poder acogerse a una devoluci\u00f3n, el art\u00edculo debe estar sin usar y en las mismas condiciones en que se recibi\u00f3. Adem\u00e1s, debe estar en su","og:url":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/","og:image":"https:\/\/ecokompass.com\/wp-content\/uploads\/2026\/07\/cropped-IMG_0654.jpg","og:image:secure_url":"https:\/\/ecokompass.com\/wp-content\/uploads\/2026\/07\/cropped-IMG_0654.jpg","og:image:width":605,"og:image:height":699,"article:published_time":"2026-07-22T18:49:48+00:00","article:modified_time":"2026-08-31T19:15:42+00:00","twitter:card":"summary_large_image","twitter:title":"Pol\u00edtica de devoluciones y reembolsos - EcoKOMPASS","twitter:description":"Nuestra pol\u00edtica de devoluciones y reembolsos tiene una duraci\u00f3n de 30 d\u00edas.Si han pasado 30 d\u00edas desde tu compra, no podemos ofrecer un reembolso completo ni un cambio del producto.Para poder acogerse a una devoluci\u00f3n, el art\u00edculo debe estar sin usar y en las mismas condiciones en que se recibi\u00f3. Adem\u00e1s, debe estar en su","twitter:image":"https:\/\/ecokompass.com\/wp-content\/uploads\/2026\/07\/cropped-IMG_0654.jpg"},"aioseo_meta_data":{"post_id":"258","title":"#post_title #separator_sa #site_title","description":"#post_content","keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-22 18:49:50","updated":"2026-08-31 19:45:27","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecokompass.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecokompass.com\/en\/tienda\/\" title=\"ECOTienda\">ECOTienda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPol\u00edtica de devoluciones y reembolsos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ecokompass.com\/en"},{"label":"ECOTienda","link":"https:\/\/ecokompass.com\/en\/tienda\/"},{"label":"Pol\u00edtica de devoluciones y reembolsos","link":"https:\/\/ecokompass.com\/en\/tienda\/reembolso_devoluciones\/"}],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/pages\/258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/comments?post=258"}],"version-history":[{"count":4,"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/pages\/258\/revisions"}],"predecessor-version":[{"id":4260,"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/pages\/258\/revisions\/4260"}],"up":[{"embeddable":true,"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/pages\/254"}],"wp:attachment":[{"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/media?parent=258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}