{"id":48,"count":2,"description":"Uso de plantas medicinales y sus extractos para prevenir o tratar patolog\u00edas.","link":"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/fitoterapia\/","name":"Herbal medicine","slug":"fitoterapia","taxonomy":"category","parent":43,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Uso de plantas medicinales y sus extractos para prevenir o tratar patolog\u00edas.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/fitoterapia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/48\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecokompass.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/category\\\/medicina-natural\\\/#listItem\",\"name\":\"Medicina Natural\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/category\\\/medicina-natural\\\/#listItem\",\"position\":2,\"name\":\"Medicina Natural\",\"item\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/category\\\/medicina-natural\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/category\\\/medicina-natural\\\/fitoterapia\\\/#listItem\",\"name\":\"Fitoterapia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/category\\\/medicina-natural\\\/fitoterapia\\\/#listItem\",\"position\":3,\"name\":\"Fitoterapia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/category\\\/medicina-natural\\\/#listItem\",\"name\":\"Medicina Natural\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/48\\\/#collectionpage\",\"url\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/48\\\/\",\"name\":\"Fitoterapia - EcoKOMPASS\",\"description\":\"Uso de plantas medicinales y sus extractos para prevenir o tratar patolog\\u00edas.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/48\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/#organization\",\"name\":\"EcoKOMPASS\",\"description\":\"Noticias  y Consejos de Salud Natural\",\"url\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ecokompass.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_0654.jpg\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/48\\\/#organizationLogo\",\"width\":893,\"height\":839},\"image\":{\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/48\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/\",\"name\":\"EcoKOMPASS\",\"description\":\"Noticias  y Consejos de Salud Natural\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecokompass.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Fitoterapia - EcoKOMPASS","description":"Uso de plantas medicinales y sus extractos para prevenir o tratar patolog\u00edas.","canonical_url":"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/fitoterapia\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/categories\/48\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/ecokompass.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/#listItem","name":"Medicina Natural"}},{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/#listItem","position":2,"name":"Medicina Natural","item":"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/fitoterapia\/#listItem","name":"Fitoterapia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/fitoterapia\/#listItem","position":3,"name":"Fitoterapia","previousItem":{"@type":"ListItem","@id":"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/#listItem","name":"Medicina Natural"}}]},{"@type":"CollectionPage","@id":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/categories\/48\/#collectionpage","url":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/categories\/48\/","name":"Fitoterapia - EcoKOMPASS","description":"Uso de plantas medicinales y sus extractos para prevenir o tratar patolog\u00edas.","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/ecokompass.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/categories\/48\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/ecokompass.com\/en\/#organization","name":"EcoKOMPASS","description":"Noticias  y Consejos de Salud Natural","url":"https:\/\/ecokompass.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/ecokompass.com\/wp-content\/uploads\/2026\/07\/IMG_0654.jpg","@id":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/categories\/48\/#organizationLogo","width":893,"height":839},"image":{"@id":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/categories\/48\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/ecokompass.com\/en\/#website","url":"https:\/\/ecokompass.com\/en\/","name":"EcoKOMPASS","description":"Noticias  y Consejos de Salud Natural","inLanguage":"en-GB","publisher":{"@id":"https:\/\/ecokompass.com\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecokompass.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/\" title=\"Medicina Natural\">Medicina Natural<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFitoterapia\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ecokompass.com\/en"},{"label":"Medicina Natural","link":"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/"},{"label":"Fitoterapia","link":"https:\/\/ecokompass.com\/en\/category\/medicina-natural\/fitoterapia\/"}],"_links":{"self":[{"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/categories\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/categories\/43"}],"wp:post_type":[{"href":"https:\/\/ecokompass.com\/en\/wp-json\/wp\/v2\/posts?categories=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}